{"id":277,"count":38,"description":"","link":"https:\/\/dc-digital.com\/wordpress\/category\/timers\/hours-timer\/","name":"Hours Timer","slug":"hours-timer","taxonomy":"category","parent":180,"meta":[],"_links":{"self":[{"href":"https:\/\/dc-digital.com\/wordpress\/wp-json\/wp\/v2\/categories\/277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dc-digital.com\/wordpress\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dc-digital.com\/wordpress\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/dc-digital.com\/wordpress\/wp-json\/wp\/v2\/categories\/180"}],"wp:post_type":[{"href":"https:\/\/dc-digital.com\/wordpress\/wp-json\/wp\/v2\/posts?categories=277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}